{"id":1926,"date":"2022-04-20T16:15:51","date_gmt":"2022-04-20T20:15:51","guid":{"rendered":"https:\/\/risklogics.org\/?page_id=1926"},"modified":"2025-11-18T09:06:54","modified_gmt":"2025-11-18T14:06:54","slug":"casino-ethnography-working-group-members","status":"publish","type":"page","link":"https:\/\/risklogics.org\/fr\/casino-ethnography-working-group-members\/","title":{"rendered":"Casino Ethnography Working Group Members"},"content":{"rendered":"<p class=\"wp-block-paragraph\">&nbsp;<\/p>\r\n\r\n\r\n<hr class=\"wp-block-separator has-css-opacity is-style-wide\" \/>\r\n\r\n\r\n<h2 class=\"wp-block-heading\">Coordinator<\/h2>\r\n\r\n\r\n\r\n<div class=\"is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\r\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\r\n<figure class=\"wp-block-image size-large is-resized is-style-editorskit-circular is-style-default\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"2001\" data-permalink=\"https:\/\/risklogics.org\/fr\/casino-ethnography-working-group-members\/erin-lynch-headshot\/\" data-orig-file=\"https:\/\/i0.wp.com\/risklogics.org\/wp-content\/uploads\/2022\/04\/Erin-Lynch-headshot-172117805-1649189808360.jpg?fit=3427%2C3457&amp;ssl=1\" data-orig-size=\"3427,3457\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Erin Lynch headshot\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/risklogics.org\/wp-content\/uploads\/2022\/04\/Erin-Lynch-headshot-172117805-1649189808360.jpg?fit=712%2C718&amp;ssl=1\" class=\"wp-image-2001 size-thumbnail alignnone alignleft\" style=\"width: 170px; height: 170px;\" src=\"https:\/\/i0.wp.com\/risklogics.org\/wp-content\/uploads\/2022\/04\/Erin-Lynch-headshot-172117805-1649189808360-150x150.jpg?resize=150%2C150&#038;ssl=1\" alt=\"\" width=\"150\" height=\"150\" srcset=\"https:\/\/i0.wp.com\/risklogics.org\/wp-content\/uploads\/2022\/04\/Erin-Lynch-headshot-172117805-1649189808360.jpg?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/risklogics.org\/wp-content\/uploads\/2022\/04\/Erin-Lynch-headshot-172117805-1649189808360.jpg?resize=1015%2C1024&amp;ssl=1 1015w, https:\/\/i0.wp.com\/risklogics.org\/wp-content\/uploads\/2022\/04\/Erin-Lynch-headshot-172117805-1649189808360.jpg?resize=768%2C775&amp;ssl=1 768w, https:\/\/i0.wp.com\/risklogics.org\/wp-content\/uploads\/2022\/04\/Erin-Lynch-headshot-172117805-1649189808360.jpg?resize=1523%2C1536&amp;ssl=1 1523w, https:\/\/i0.wp.com\/risklogics.org\/wp-content\/uploads\/2022\/04\/Erin-Lynch-headshot-172117805-1649189808360.jpg?resize=2030%2C2048&amp;ssl=1 2030w, https:\/\/i0.wp.com\/risklogics.org\/wp-content\/uploads\/2022\/04\/Erin-Lynch-headshot-172117805-1649189808360.jpg?resize=1200%2C1211&amp;ssl=1 1200w, https:\/\/i0.wp.com\/risklogics.org\/wp-content\/uploads\/2022\/04\/Erin-Lynch-headshot-172117805-1649189808360.jpg?resize=800%2C800&amp;ssl=1 800w, https:\/\/i0.wp.com\/risklogics.org\/wp-content\/uploads\/2022\/04\/Erin-Lynch-headshot-172117805-1649189808360.jpg?resize=400%2C400&amp;ssl=1 400w, https:\/\/i0.wp.com\/risklogics.org\/wp-content\/uploads\/2022\/04\/Erin-Lynch-headshot-172117805-1649189808360.jpg?resize=200%2C200&amp;ssl=1 200w, https:\/\/i0.wp.com\/risklogics.org\/wp-content\/uploads\/2022\/04\/Erin-Lynch-headshot-172117805-1649189808360.jpg?resize=1568%2C1582&amp;ssl=1 1568w, https:\/\/i0.wp.com\/risklogics.org\/wp-content\/uploads\/2022\/04\/Erin-Lynch-headshot-172117805-1649189808360.jpg?w=1424&amp;ssl=1 1424w, https:\/\/i0.wp.com\/risklogics.org\/wp-content\/uploads\/2022\/04\/Erin-Lynch-headshot-172117805-1649189808360.jpg?w=2136&amp;ssl=1 2136w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/figure>\r\n<\/div>\r\n\r\n\r\n\r\n<div class=\"is-layout-flow wp-block-column-is-layout-flow\">\r\n<p class=\"wp-block-paragraph\" style=\"text-align: left;\"><strong>Erin Lynch<\/strong><\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\" style=\"text-align: left;\"><strong>Research interests:<\/strong>\u00a0sensory ethnography, locative tourism applications<\/p>\r\n\r\n\r\n<\/div>\r\n\r\n\r\n\r\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\u00a0<\/div>\r\n\r\n\r\n\r\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\u00a0<\/div>\r\n<\/div>\r\n\r\n\r\n\r\n<h2 class=\"wp-block-heading\">\u00a0<\/h2>\r\n<h2 class=\"wp-block-heading\">Team Members<\/h2>\r\n\r\n\r\n\r\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\r\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\r\n<figure class=\"wp-block-image is-style-editorskit-circular size-full is-resized is-style-default\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"2026\" data-permalink=\"https:\/\/risklogics.org\/fr\/casino-ethnography-working-group-members\/amrita-gurung-headshot-2\/\" data-orig-file=\"https:\/\/i0.wp.com\/risklogics.org\/wp-content\/uploads\/2022\/04\/Amrita-Gurung-headshot-e1763473723117.jpg?fit=506%2C479&amp;ssl=1\" data-orig-size=\"506,479\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"Amrita-Gurung-headshot\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/risklogics.org\/wp-content\/uploads\/2022\/04\/Amrita-Gurung-headshot-e1763473723117.jpg?fit=506%2C479&amp;ssl=1\" class=\"wp-image-2026 size-thumbnail alignnone\" style=\"width: 170px; height: 171px;\" src=\"https:\/\/i0.wp.com\/risklogics.org\/wp-content\/uploads\/2022\/04\/Amrita-Gurung-headshot-e1763473723117-150x150.jpg?resize=150%2C150&#038;ssl=1\" alt=\"\" width=\"150\" height=\"150\" srcset=\"https:\/\/i0.wp.com\/risklogics.org\/wp-content\/uploads\/2022\/04\/Amrita-Gurung-headshot-e1763473723117.jpg?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/risklogics.org\/wp-content\/uploads\/2022\/04\/Amrita-Gurung-headshot-e1763473723117.jpg?resize=13%2C12&amp;ssl=1 13w, https:\/\/i0.wp.com\/risklogics.org\/wp-content\/uploads\/2022\/04\/Amrita-Gurung-headshot-e1763473723117.jpg?resize=75%2C75&amp;ssl=1 75w, https:\/\/i0.wp.com\/risklogics.org\/wp-content\/uploads\/2022\/04\/Amrita-Gurung-headshot-e1763473723117.jpg?zoom=2&amp;resize=150%2C150&amp;ssl=1 300w, https:\/\/i0.wp.com\/risklogics.org\/wp-content\/uploads\/2022\/04\/Amrita-Gurung-headshot-e1763473723117.jpg?zoom=3&amp;resize=150%2C150&amp;ssl=1 450w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/figure>\r\n<p style=\"text-align: left;\"><strong>Amrita Gurung<\/strong><\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\" style=\"text-align: left;\"><strong>Research interests:\u00a0<\/strong>transnational mobilities, emotionality, risk, gambling, environment, infrastructure, Nepal and Himalayan studies<\/p>\r\n\r\n\r\n<\/div>\r\n\r\n\r\n\r\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\r\n<figure><\/figure>\r\n<figure><\/figure>\r\n<figure class=\"wp-block-image is-style-editorskit-circular size-large is-resized is-style-default\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"2030\" data-permalink=\"https:\/\/risklogics.org\/fr\/casino-ethnography-working-group-members\/rptnb-2\/\" data-orig-file=\"https:\/\/i0.wp.com\/risklogics.org\/wp-content\/uploads\/2022\/04\/Genevieve-Collins-headshot-1.jpg?fit=2312%2C2011&amp;ssl=1\" data-orig-size=\"2312,2011\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;1.6&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;VOG-L04&quot;,&quot;caption&quot;:&quot;rptnb&quot;,&quot;created_timestamp&quot;:&quot;1624624728&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;5.56&quot;,&quot;iso&quot;:&quot;50&quot;,&quot;shutter_speed&quot;:&quot;0.001471&quot;,&quot;title&quot;:&quot;rptnb&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"rptnb\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;rptnb&lt;\/p&gt;\" data-large-file=\"https:\/\/i0.wp.com\/risklogics.org\/wp-content\/uploads\/2022\/04\/Genevieve-Collins-headshot-1.jpg?fit=712%2C620&amp;ssl=1\" class=\"wp-image-2030 size-thumbnail alignnone\" style=\"width: 170px; height: 170px;\" src=\"https:\/\/i0.wp.com\/risklogics.org\/wp-content\/uploads\/2022\/04\/Genevieve-Collins-headshot-1-150x150.jpg?resize=150%2C150&#038;ssl=1\" alt=\"\" width=\"150\" height=\"150\" srcset=\"https:\/\/i0.wp.com\/risklogics.org\/wp-content\/uploads\/2022\/04\/Genevieve-Collins-headshot-1.jpg?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/risklogics.org\/wp-content\/uploads\/2022\/04\/Genevieve-Collins-headshot-1.jpg?resize=1200%2C1200&amp;ssl=1 1200w, https:\/\/i0.wp.com\/risklogics.org\/wp-content\/uploads\/2022\/04\/Genevieve-Collins-headshot-1.jpg?resize=800%2C800&amp;ssl=1 800w, https:\/\/i0.wp.com\/risklogics.org\/wp-content\/uploads\/2022\/04\/Genevieve-Collins-headshot-1.jpg?resize=400%2C400&amp;ssl=1 400w, https:\/\/i0.wp.com\/risklogics.org\/wp-content\/uploads\/2022\/04\/Genevieve-Collins-headshot-1.jpg?resize=200%2C200&amp;ssl=1 200w, https:\/\/i0.wp.com\/risklogics.org\/wp-content\/uploads\/2022\/04\/Genevieve-Collins-headshot-1.jpg?zoom=2&amp;resize=150%2C150&amp;ssl=1 300w, https:\/\/i0.wp.com\/risklogics.org\/wp-content\/uploads\/2022\/04\/Genevieve-Collins-headshot-1.jpg?zoom=3&amp;resize=150%2C150&amp;ssl=1 450w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/figure>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\" style=\"text-align: left;\"><strong>Genevieve Collins<\/strong><\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\" style=\"text-align: left;\"><strong>Research interests:<\/strong>\u00a0sensory anthropology, futures anthropology<\/p>\r\n\r\n\r\n<\/div>\r\n<\/div>\r\n\r\n\r\n\r\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\r\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\r\n<figure><\/figure>\r\n<figure><\/figure>\r\n<figure class=\"wp-block-image is-style-editorskit-circular size-large is-resized\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"2059\" data-permalink=\"https:\/\/risklogics.org\/fr\/casino-ethnography-working-group-members\/isabella-byrne-headshot-6\/\" data-orig-file=\"https:\/\/i0.wp.com\/risklogics.org\/wp-content\/uploads\/2022\/04\/Isabella-Byrne-Headshot-6.jpg?fit=1079%2C1430&amp;ssl=1\" data-orig-size=\"1079,1430\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;2.2&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;iPhone 8 Plus&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1630883407&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;2.87&quot;,&quot;iso&quot;:&quot;250&quot;,&quot;shutter_speed&quot;:&quot;0.025&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"Isabella-Byrne-Headshot-6\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/risklogics.org\/wp-content\/uploads\/2022\/04\/Isabella-Byrne-Headshot-6.jpg?fit=712%2C943&amp;ssl=1\" class=\"wp-image-2059 size-thumbnail alignnone\" style=\"width: 170px; height: 170px;\" src=\"https:\/\/i0.wp.com\/risklogics.org\/wp-content\/uploads\/2022\/04\/Isabella-Byrne-Headshot-6-150x150.jpg?resize=150%2C150&#038;ssl=1\" alt=\"\" width=\"150\" height=\"150\" srcset=\"https:\/\/i0.wp.com\/risklogics.org\/wp-content\/uploads\/2022\/04\/Isabella-Byrne-Headshot-6.jpg?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/risklogics.org\/wp-content\/uploads\/2022\/04\/Isabella-Byrne-Headshot-6.jpg?resize=800%2C800&amp;ssl=1 800w, https:\/\/i0.wp.com\/risklogics.org\/wp-content\/uploads\/2022\/04\/Isabella-Byrne-Headshot-6.jpg?resize=400%2C400&amp;ssl=1 400w, https:\/\/i0.wp.com\/risklogics.org\/wp-content\/uploads\/2022\/04\/Isabella-Byrne-Headshot-6.jpg?resize=200%2C200&amp;ssl=1 200w, https:\/\/i0.wp.com\/risklogics.org\/wp-content\/uploads\/2022\/04\/Isabella-Byrne-Headshot-6.jpg?zoom=2&amp;resize=150%2C150&amp;ssl=1 300w, https:\/\/i0.wp.com\/risklogics.org\/wp-content\/uploads\/2022\/04\/Isabella-Byrne-Headshot-6.jpg?zoom=3&amp;resize=150%2C150&amp;ssl=1 450w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/figure>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\" style=\"text-align: left;\"><strong>Isabella Byrne<\/strong><\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\" style=\"text-align: left;\"><strong>Research interests:<\/strong>\u00a0pilgrimage and ethnography in video games, sensorial dimensions of online poker<\/p>\r\n\r\n\r\n<\/div>\r\n\r\n\r\n\r\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\r\n<figure><\/figure>\r\n<figure><\/figure>\r\n<figure class=\"wp-block-image is-style-editorskit-circular size-large is-resized\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" data-attachment-id=\"2039\" data-permalink=\"https:\/\/risklogics.org\/fr\/casino-ethnography-working-group-members\/pierre-olivier-jourdenais-headshot-1\/\" data-orig-file=\"https:\/\/i0.wp.com\/risklogics.org\/wp-content\/uploads\/2022\/04\/Pierre-Olivier-Jourdenais-headshot-1.jpeg?fit=1440%2C1430&amp;ssl=1\" data-orig-size=\"1440,1430\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Pierre-Olivier-Jourdenais-headshot-1\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/risklogics.org\/wp-content\/uploads\/2022\/04\/Pierre-Olivier-Jourdenais-headshot-1.jpeg?fit=712%2C707&amp;ssl=1\" class=\"wp-image-2039 size-thumbnail alignnone\" style=\"width: 170px; height: 170px;\" src=\"https:\/\/i0.wp.com\/risklogics.org\/wp-content\/uploads\/2022\/04\/Pierre-Olivier-Jourdenais-headshot-1-150x150.jpeg?resize=150%2C150&#038;ssl=1\" alt=\"\" width=\"150\" height=\"150\" srcset=\"https:\/\/i0.wp.com\/risklogics.org\/wp-content\/uploads\/2022\/04\/Pierre-Olivier-Jourdenais-headshot-1.jpeg?resize=150%2C150&amp;ssl=1 150w, https:\/\/i0.wp.com\/risklogics.org\/wp-content\/uploads\/2022\/04\/Pierre-Olivier-Jourdenais-headshot-1.jpeg?resize=300%2C298&amp;ssl=1 300w, https:\/\/i0.wp.com\/risklogics.org\/wp-content\/uploads\/2022\/04\/Pierre-Olivier-Jourdenais-headshot-1.jpeg?resize=1024%2C1017&amp;ssl=1 1024w, https:\/\/i0.wp.com\/risklogics.org\/wp-content\/uploads\/2022\/04\/Pierre-Olivier-Jourdenais-headshot-1.jpeg?resize=768%2C763&amp;ssl=1 768w, https:\/\/i0.wp.com\/risklogics.org\/wp-content\/uploads\/2022\/04\/Pierre-Olivier-Jourdenais-headshot-1.jpeg?resize=12%2C12&amp;ssl=1 12w, https:\/\/i0.wp.com\/risklogics.org\/wp-content\/uploads\/2022\/04\/Pierre-Olivier-Jourdenais-headshot-1.jpeg?resize=1200%2C1192&amp;ssl=1 1200w, https:\/\/i0.wp.com\/risklogics.org\/wp-content\/uploads\/2022\/04\/Pierre-Olivier-Jourdenais-headshot-1.jpeg?resize=800%2C800&amp;ssl=1 800w, https:\/\/i0.wp.com\/risklogics.org\/wp-content\/uploads\/2022\/04\/Pierre-Olivier-Jourdenais-headshot-1.jpeg?resize=400%2C400&amp;ssl=1 400w, https:\/\/i0.wp.com\/risklogics.org\/wp-content\/uploads\/2022\/04\/Pierre-Olivier-Jourdenais-headshot-1.jpeg?resize=200%2C200&amp;ssl=1 200w, https:\/\/i0.wp.com\/risklogics.org\/wp-content\/uploads\/2022\/04\/Pierre-Olivier-Jourdenais-headshot-1.jpeg?w=1440&amp;ssl=1 1440w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/figure>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\" style=\"text-align: left;\"><strong>Pierre-Olivier Jourdenais<\/strong><\/p>\r\n\r\n\r\n\r\n<p class=\"wp-block-paragraph\" style=\"text-align: left;\"><strong>Research interests:<\/strong>\u00a0sexuality and relationship norms, gambling, queer studies, the search for \u2018meaning\u2019 in one\u2019s life, and politics\/political sociology<\/p>\r\n\r\n\r\n<\/div>\r\n<\/div>","protected":false},"excerpt":{"rendered":"<p>&nbsp; Coordinator Erin Lynch Research interests:\u00a0sensory ethnography, locative tourism applications \u00a0 \u00a0 \u00a0 Team Members Research interests:\u00a0transnational mobilities, emotionality, risk, gambling, environment, infrastructure, Nepal and Himalayan studies Genevieve Collins Research interests:\u00a0sensory anthropology, futures anthropology Isabella Byrne Research interests:\u00a0pilgrimage and ethnography in video games, sensorial dimensions of online poker Pierre-Olivier Jourdenais Research interests:\u00a0sexuality and relationship norms, &hellip; <a href=\"https:\/\/risklogics.org\/fr\/casino-ethnography-working-group-members\/\" class=\"more-link\">Continuer la lecture de <span class=\"screen-reader-text\">Casino Ethnography Working Group Members<\/span><\/a><\/p>","protected":false},"author":127400573,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_editorskit_title_hidden":false,"_editorskit_reading_time":0,"_editorskit_is_block_options_detached":false,"_editorskit_block_options_position":"{}","_coblocks_attr":"","_coblocks_dimensions":"","_coblocks_responsive_height":"","_coblocks_accordion_ie_support":"","_crdt_document":"","advanced_seo_description":"","jetpack_seo_html_title":"","jetpack_seo_noindex":false,"footnotes":""},"tags":[],"class_list":["post-1926","page","type-page","status-publish","hentry","no-featured-image"],"jetpack_likes_enabled":true,"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/Pd3Xs2-v4","amp_enabled":true,"_links":{"self":[{"href":"https:\/\/risklogics.org\/fr\/wp-json\/wp\/v2\/pages\/1926","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/risklogics.org\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/risklogics.org\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/risklogics.org\/fr\/wp-json\/wp\/v2\/users\/127400573"}],"replies":[{"embeddable":true,"href":"https:\/\/risklogics.org\/fr\/wp-json\/wp\/v2\/comments?post=1926"}],"version-history":[{"count":24,"href":"https:\/\/risklogics.org\/fr\/wp-json\/wp\/v2\/pages\/1926\/revisions"}],"predecessor-version":[{"id":5837,"href":"https:\/\/risklogics.org\/fr\/wp-json\/wp\/v2\/pages\/1926\/revisions\/5837"}],"wp:attachment":[{"href":"https:\/\/risklogics.org\/fr\/wp-json\/wp\/v2\/media?parent=1926"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/risklogics.org\/fr\/wp-json\/wp\/v2\/tags?post=1926"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}